{"id":305,"date":"2018-07-18T13:47:45","date_gmt":"2018-07-18T11:47:45","guid":{"rendered":"https:\/\/tidjaniya.com\/fr\/?p=305"},"modified":"2018-07-18T13:47:45","modified_gmt":"2018-07-18T11:47:45","slug":"question-reponse-29","status":"publish","type":"post","link":"https:\/\/tidjaniya.com\/fr\/question-reponse-29\/","title":{"rendered":"Question-r\u00e9ponse 29"},"content":{"rendered":"<div class=\"content-text\">\n<p style=\"text-align: justify;\"><strong><span class=\"tgras\">Pourriez-vous me renseigner au sujet de la posture des bras crois\u00e9es (qabdh) ou allong\u00e9es (Sadl) au cours de la pri\u00e8re ? Est-ce vrai que la posture allong\u00e9e n&rsquo;a aucun fondement dans la Sunna ?<\/span><\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong><span class=\"tgras\">REPONSE<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Le savant et <strong>Cheikh <span class=\"tgras\">Hajj Makki Abdallah Tidjani<\/span><\/strong> a dit : \u00ab Certains \u00e9tudiants en science d\u2019ob\u00e9dience Wahhabites disent et pr\u00e9tendent que les Malikites allongent les bras le long du corps pendant la pri\u00e8re sans avoir aucune preuve, alors que le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) croisait les bras pendant la pri\u00e8re et il y a des hadiths authentiques qui confirment le Qabdh. Les compagnons (qu\u2019Allah les agr\u00e9e) et les suivants croisaient eux aussi les bras pendant la pri\u00e8re et nulle part il n\u2019est mentionn\u00e9 qu\u2019ils allongeaient les bras pendant la pri\u00e8re, jusqu\u2019\u00e0 l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) qui est \u00e0 l\u2019origine de cette \u00e9cole. Il croisait lui aussi les bras pendant la pri\u00e8re jusqu\u2019au jour o\u00f9 il fut frapp\u00e9 et alors il n\u2019arrivait plus \u00e0 les croiser, il allongeait donc les bras et c\u2019est \u00e0 cause de cela que ses compagnons, par la suite, l\u2019ont suivi et ont allong\u00e9 les bras d\u00e9clarants comme d\u00e9testable (Makrouh) dans leurs \u00e9coles le fait de croiser les bras sans aucune preuve pour cela \u00bb.<\/p>\n<p style=\"text-align: justify;\">Nous r\u00e9pondons :<\/p>\n<p style=\"text-align: justify;\">Allah (qu\u2019Il soit Glorifi\u00e9 et Exalt\u00e9) dit <span class=\"coran\">: \u00ab<span style=\"color: #0000ff;\"><strong> Et si tu ob\u00e9is \u00e0 la majorit\u00e9 de ceux qui sont sur la terre, ils t\u2019\u00e9gareront du sentier d\u2019Allah, ils ne suivent que la conjecture et ne font que fabriquer des mensonges<\/strong> <\/span>\u00bb (Sourate 06 Les bestiaux, verset 116).<\/span><\/p>\n<p style=\"text-align: justify;\">Nous disons que leur propos n\u2019est qu\u2019inventions de leur part, un mensonge et une injustice contre le ma\u00eetre des Imams, l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e). [\u2026] si c\u2019est en raison du fait qu\u2019ils n\u2019ont pas consult\u00e9 les preuves argumentant en faveur de l\u2019allongement des bras, ils doivent alors se r\u00e9f\u00e9rer aux livres de la Sunna et leurs commentaires et ceux des juristes qui suivent l\u2019\u00e9cole des Imams.<\/p>\n<p style=\"text-align: justify;\">Allah (qu\u2019Il soit Glorifi\u00e9 et Exalt\u00e9) dit : <span class=\"coran\">\u00ab<strong><span style=\"color: #0000ff;\"> [\u2026] ils ont trait\u00e9 de mensonge ce qu\u2019ils ne peuvent embrasser de leur savoir et dont l\u2019interpr\u00e9tation ne leur est pas encore parvenue\u2026<\/span> <\/strong>\u00bb (Sourate 10 Jonas, verset 39).<\/span><\/p>\n<p style=\"text-align: justify;\">Allah (qu\u2019Il soit Glorifi\u00e9 et Exalt\u00e9) dit<span class=\"coran\"> : \u00ab<span style=\"color: #0000ff;\"><strong> Et ne poursuis pas ce dont tu n\u2019as aucune connaissance [\u2026]<\/strong><\/span> \u00bb (Sourate 17 Le voyage nocturne, verset 36).<\/span><\/p>\n<p style=\"text-align: justify;\">Nous voulons demander \u00e0 ceux qui lancent cette critique et nous esp\u00e9rons une r\u00e9ponse :<\/p>\n<p style=\"text-align: justify;\"><strong><span class=\"tgras\">Premi\u00e8rement<\/span> <\/strong>: Que pensez-vous de l\u2019allongement des bras de ce noble compagnon Abdallah ibn Zoube\u00efr (qu\u2019Allah l\u2019agr\u00e9e), un des quatre c\u00e9l\u00e8bres <span class=\"tgras\">Abdallah<\/span> qui pouvaient donner des d\u00e9crets juridiques (Fatwa) au temps des compagnons (qu\u2019Allah les agr\u00e9e). \u00c0 la m\u00eame \u00e9poque, on disait : \u00ab<span class=\"paroles\" style=\"color: #800000;\"> C\u2019est la parole de l\u2019un des Abdallah<\/span> \u00bb et cela d\u00e9signait Abdallah <span class=\"tgras\">ibn Zoube\u00efr<\/span>, Abdallah<span class=\"tgras\"> ibn \u2018Abbas<\/span>, Abdallah<span class=\"tgras\"> ibn Omar <\/span>et Abdallah<span class=\"tgras\"> ibn \u2018Amr ibn El \u2018As<\/span> (qu\u2019Allah les agr\u00e9e). Et Abdallah ibn \u2018Abbas a attest\u00e9 que la pri\u00e8re d\u2019Ibn Zoube\u00efr (qu\u2019Allah les agr\u00e9e) est exactement la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui).<\/p>\n<p style=\"text-align: justify;\">Il est dit dans <strong><span class=\"tgras\">Ibram Naqadh <\/span><\/strong>: \u00ab Il est \u00e9tabli aupr\u00e8s des savants qu\u2019Ibn Zoube\u00efr (qu\u2019Allah l\u2019agr\u00e9e) allongeait les bras pendant la pri\u00e8re et il faut savoir que par l\u2019attestation d\u2019Ibn \u2018Abbas sur lui, sa pri\u00e8re est exactement la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui), donc le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) allongeait les bras pendant la pri\u00e8re et cela prouve que le fait de croiser les bras a \u00e9t\u00e9 abrog\u00e9.<\/p>\n<p style=\"text-align: justify;\">Tout comme il est dit par les Hanafites aussi, que les hadiths stipulant qu\u2019il faut lever les mains pour s\u2019incliner et pour se relever de l\u2019inclinaison ont \u00e9t\u00e9 abrog\u00e9s puisqu\u2019il a \u00e9t\u00e9 \u00e9tabli pour eux d\u2019autres hadiths et faits de compagnons (Athar) authentiques. Parmi ceux-l\u00e0 le hadith de Abdallah ibn Mess\u2019oud (qu\u2019Allah l\u2019agr\u00e9e) qui a dit : \u00ab <span class=\"paroles\">N<span style=\"color: #800000;\">e vais-je pas prier devant vous \u00e0 la mani\u00e8re dont priait le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) ?<\/span> \u00bb<\/span> Il a donc pri\u00e9 et n\u2019a lev\u00e9 les mains qu\u2019au d\u00e9but \u00bb (rapport\u00e9 par Tirmidhi avec une cha\u00eene bonne).<\/p>\n<p style=\"text-align: justify;\">Dans<strong> <span class=\"tgras\">Aoujaz El Masalik <\/span><\/strong>il est dit : \u00ab<span class=\"paroles\" style=\"color: #800000;\"> Quant aux quatre Khalifes il n\u2019est pas \u00e9tabli qu\u2019ils \u00e9levaient les mains en dehors du Takbir de sacralisation (<span class=\"tgras\">Takbirat El Ihram<\/span>) <\/span>\u00bb<\/p>\n<p style=\"text-align: justify;\">Il est dit dans <strong><span class=\"tgras\">Bada-i<\/span><\/strong> : \u00ab <span style=\"color: #800000;\">Il est rapport\u00e9 qu\u2019Ibn \u2018Abbas (qu\u2019Allah l\u2019agr\u00e9e) a dit : \u00ab <span class=\"paroles\">Les dix compagnons auxquels le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) a garanti le Paradis ne levaient leurs mains que pour d\u00e9buter la pri\u00e8re <\/span>\u00bb<\/span> \u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong><span class=\"tgras\">Deuxi\u00e8mement<\/span> <\/strong>: Que pensez-vous de l\u2019allongement des bras de Hassan Basri, Nakha\u2019i et Ibn Sirrin (qu\u2019Allah les agr\u00e9e) ?<\/p>\n<p style=\"text-align: justify;\">Layth ibn Sa\u2019d a dit : <span class=\"paroles\">\u00ab <span style=\"color: #800000;\">Il faut allonger les bras et si la pri\u00e8re se prolonge trop pour lui alors il met sa main droite sur sa main gauche afin de se reposer<\/span> \u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\">El Aouza\u2019i a dit : \u00ab <span class=\"paroles\"><span style=\"color: #800000;\">C\u2019est la raison du choix qui existe entre tenir les bras ou les allonger<\/span> <\/span>\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong><span class=\"tgras\">Troisi\u00e8mement<\/span> <\/strong>: Que pensez-vous de l\u2019allongement des bras de Sa\u2019id ibn el Moussayeb (qu\u2019Allah l\u2019agr\u00e9e) durant la pri\u00e8re, alors qu\u2019il est consid\u00e9r\u00e9 par les gens de M\u00e9dine comme le meilleur parmi les suivants (Tabi\u2019ine). Il \u00e9tait l\u2019un des sept juristes et les savants sont unanimes sur son honneur, sa loyaut\u00e9 et sa pr\u00e9\u00e9minence par rapport aux gens de son \u00e9poque dans la science, dans les m\u00e9rites et les divers aspects du bien. Il \u00e9tait \u00e0 la t\u00eate des gens de M\u00e9dine de son si\u00e8cle, prioritaire dans les Fatwas et il fut nomm\u00e9 le ma\u00eetre des juristes faisant partie des suivants dont Allah (qu\u2019Il soit Glorifi\u00e9 et Exalt\u00e9) a dit : <span class=\"coran\">\u00ab <strong><span style=\"color: #0000ff;\">Les tout premiers parmi les Emigr\u00e9s et les Auxiliaires et ceux qui les ont suivis dans l\u2019excellence<\/span><\/strong> \u00bb (Sourate 09 Le repentir, verset 100).<\/span><\/p>\n<p style=\"text-align: justify;\">Et la Sunna t\u00e9moigne en leur faveur en disant : <span class=\"hadith\">\u00ab<strong> L<span style=\"color: #800000;\">es meilleurs si\u00e8cles sont le mien ensuite celui qui le suit [\u2026]<\/span><\/strong> \u00bb<\/span>(Unanimement reconnu authentique) et la parole du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) o\u00f9 il dit : <span class=\"hadith\">\u00ab <span style=\"color: #800000;\"><strong>Bienheureux ceux qui m\u2019ont vu et ont cru en moi et bienheureux ceux qui ont vu ceux qui m\u2019ont vu<\/strong> <\/span>\u00bb <\/span>(rapport\u00e9 par Ahmed et autres).<\/p>\n<p style=\"text-align: justify;\">Nous disons donc : est-ce que l\u2019allongement des bras de ces savants Imams parmi les suivants et avec avant eux le compagnon Abdallah ibn Zoube\u00efr (qu\u2019Allah l\u2019agr\u00e9e) est en raison de leur ignorance de la Sunna ou suivaient-ils alors leurs passions ou encore \u00e9taient-ils tous atteints de paralysie comme cela a \u00e9t\u00e9 invent\u00e9 au sujet de l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) ou bien existe-t-il un autre pr\u00e9texte ? Faites-nous donc profiter et donnez-nous vos arguments si vous \u00eates v\u00e9ridiques.<\/p>\n<p style=\"text-align: justify;\">Il faut savoir que l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) a connu 300 personnes de la g\u00e9n\u00e9ration des Suivants (Tabi\u2019ine) \u00e0 M\u00e9dine avec parmi eux les juristes. Il a pris d\u2019eux en donnant la pr\u00e9\u00e9minence \u00e0 leurs \u0153uvres face aux hadiths authentiques du fait qu\u2019il est certifi\u00e9, comme rapport\u00e9 dans le <span class=\"tgras\">Mou-ata <\/span>et le <span class=\"tgras\">Sahih Boukhari,<\/span> que les compagnons (qu\u2019Allah les agr\u00e9e) ont pris les derniers actes accomplis par le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) et c\u2019est ce qui \u00e9tait valid\u00e9 et pratiqu\u00e9 par les juristes de M\u00e9dine. Cela est une Sunna h\u00e9rit\u00e9e de l\u2019action du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) \u00ab <span class=\"tgras\">Sunna \u2018Amaliya <\/span>\u00bb et c\u2019est plus fort qu\u2019une Sunna h\u00e9rit\u00e9e par la parole \u00ab <span class=\"tgras\">Sunna Qaouliya <\/span>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il est certifi\u00e9 par les savants que l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) a rapport\u00e9 des hadiths dans le <span class=\"tgras\">Mou-ata<\/span> alors qu\u2019il ne les prenait pas en compte et cela parce que ce qui \u00e9tait valid\u00e9 et pratiqu\u00e9 par les juristes de M\u00e9dine allait \u00e0 leur encontre. Or eux-m\u00eames n\u2019ont fait que suivre les compagnons du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) qui \u00e9taient justement les plus inform\u00e9s sur ce que le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) a laiss\u00e9.<\/p>\n<p style=\"text-align: justify;\">Cheikh Mohamed Habiboullah a relat\u00e9 dans <strong><span class=\"tgras\">Ida-at El Halek<\/span><\/strong> : \u00ab<span style=\"color: #800000;\"> [\u2026] et comme le dit Ibn Hazm dans le livre <span class=\"tgras\">Maratib Dayana<\/span> : \u00ab <span class=\"paroles\">L\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) a d\u00e9laiss\u00e9 la pratique de soixante-dix hadiths qu\u2019il rapporte pourtant dans son <span class=\"tgras\">Moua-ta<\/span><\/span> <\/span>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Sidi Mohamed El Hafidh a dit dans la revue <strong><span class=\"tgras\">Tariq El Haqq<\/span><\/strong> : \u00ab Dans le commentaire du collecteur de <span class=\"tgras\">Nawawi<\/span>, apr\u00e8s avoir mentionn\u00e9 l\u2019\u00e9cole Chafi\u2019i et le m\u00e9rite qu\u2019elle accorde au fait d\u2019empoigner les bras, il a dit :<\/p>\n<p style=\"text-align: justify;\">\u00ab Il est rapport\u00e9 par Ibn Moundher que Abdallah ibn Zoube\u00efr, Hassan Basri et Nakha\u2019i (qu\u2019Allah les agr\u00e9e) allongeaient leur bras au cours de la pri\u00e8re et ne posaient pas la main l\u2019une sur l\u2019autre. Le Qadi Abou Ta\u00efeb a rapport\u00e9 la m\u00eame chose concernant Ibn Sirrin. Et Layth ibn Sa\u2019d a dit : \u00ab<span class=\"paroles\" style=\"color: #800000;\"> Il faut allonger les bras et si la pri\u00e8re se prolonge trop pour lui alors il met sa main droite sur sa main gauche afin de se reposer<\/span> \u00bb.<\/p>\n<p style=\"text-align: justify;\">El Khatib a rapport\u00e9 dans <strong><span class=\"tgras\">Tarikh Baghdad<\/span><\/strong> selon l\u2019Imam Ahmed qu\u2019il a dit :<\/p>\n<p style=\"text-align: justify;\">\u00ab<span class=\"paroles\" style=\"color: #800000;\"> Abdrazzaq m\u2019a inform\u00e9 que les gens de la Mecque disent qu\u2019Ibn Joureyj a recueilli la mani\u00e8re de prier de \u2018Ata, et \u2018Ata l\u2019a recueilli de Abdallah ibn Zoube\u00efr (qu\u2019Allah l\u2019agr\u00e9e) et Ibn Zoube\u00efr l\u2019a recueilli de Abou Bakr Siddiq (qu\u2019Allah l\u2019agr\u00e9e) et Abou Bakr l\u2019a recueilli du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui). <\/span>\u00bb<\/p>\n<p style=\"text-align: justify;\">El Hafidh Mohamed ibn Soule\u00efman Raoudani rapporte dans <span class=\"tgras\">Fawa-id\u2026Zawa-id<\/span> qui rassemble les hadiths rapport\u00e9s dans le <span class=\"tgras\">Moua-ta<\/span>, dans les deux <span class=\"tgras\">Sahih<\/span> et les <span class=\"tgras\">Sunan<\/span>, dans le <span class=\"tgras\">Mousnad<\/span> de l\u2019Imam Ahmed, Darami, Abou Ya\u2019la, El Moussouli, El Bazzar et le <span class=\"tgras\">Mou\u2019jam<\/span> de Tabarani\u2026 qu\u2019une personne a interrog\u00e9 <span class=\"tgras\">Ibn \u2018Abbas<\/span> (qu\u2019Allah l\u2019agr\u00e9e), il lui dit : \u00ab <span style=\"color: #800000;\"><span class=\"paroles\">J\u2019ai vu Ibn Zoube\u00efr faire une pri\u00e8re que je n\u2019ai vu personne avant lui faire \u00bb. <\/span>Il lui r\u00e9pondit : <\/span><span class=\"paroles\"><span style=\"color: #800000;\">\u00ab Si tu veux voir la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) alors conforme-toi \u00e0 la pri\u00e8re d\u2019Ibn Zoube\u00efr<\/span> \u00bb<\/span>.<\/p>\n<p style=\"text-align: justify;\">L\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) a bien rapport\u00e9 le hadith sur le Qabdh dans son <span class=\"tgras\">Mou-ata<\/span> mais il ne le prenait pas en compte et ce, du fait que la majorit\u00e9 des agissements accomplis par les juristes de M\u00e9dine sont les derniers agissements du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) puisqu\u2019il est certifi\u00e9 que ses compagnons (qu\u2019Allah les agr\u00e9e) agissaient en cons\u00e9quence des derniers actes accomplis par le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui). Or c\u2019est ce fondement qui est pris en compte dans les agissements des juristes de M\u00e9dine. Cela est donc une Sunna h\u00e9rit\u00e9e par les actes que le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) a laiss\u00e9s \u00e0 ses compagnons (qu\u2019Allah les agr\u00e9e) et c\u2019est plus solide qu\u2019une Sunna h\u00e9rit\u00e9e par la parole.<\/p>\n<p style=\"text-align: justify;\">Les savants sont unanimes pour dire que l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) a rapport\u00e9 des hadiths dans son <span class=\"tgras\">Mou-ata<\/span> qu\u2019il ne prenait pas en consid\u00e9ration compte tenu du fait que les agissements des juristes de M\u00e9dine les contredisaient. Or ils n\u2019ont fait que reproduire ce qu\u2019ont fait les compagnons (qu\u2019Allah les agr\u00e9e) et ils \u00e9taient les mieux inform\u00e9s de ce que le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) a laiss\u00e9 \u00e0 ses compagnons.<\/p>\n<p style=\"text-align: justify;\">De plus, leur \u00e9poque n\u2019\u00e9tait point \u00e9loign\u00e9e par une longue p\u00e9riode de celle des compagnons (qu\u2019Allah les agr\u00e9e), car il n\u2019y avait entre l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) et les compagnons qu\u2019un seul interm\u00e9diaire qui est Nafi\u2019 qui lui a connu Ibn \u2018Omar (qu\u2019Allah l\u2019agr\u00e9e) et de lui au Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui).<\/p>\n<p style=\"text-align: justify;\">Cheikh <span class=\"tgras\">Mohamed El Hafidh<\/span> a dit :<\/p>\n<p style=\"text-align: justify;\">\u00ab Concernant la lev\u00e9e des mains lorsqu\u2019on rel\u00e8ve sa t\u00eate, la proclamation \u00e0 haute voix du \u00ab AMIN \u00bb ainsi que le croisement des bras pendant la pri\u00e8re, c\u2019est ce qui est fait dans l\u2019\u00e9cole Chafi\u2019ite et il est permis au Malikite d\u2019imiter les Chafi\u2019ite en cela, car il est rapport\u00e9 \u00e0 ce sujet des hadiths authentiques. Or l\u2019\u00e9cole Chafi\u2019ite prend comme r\u00e8gle la conformit\u00e9 aux hadiths authentiques.<\/p>\n<p style=\"text-align: justify;\">Concernant l\u2019\u00e9cole Malikite, parmi ses fondements, il y a la conformit\u00e9 aux \u0153uvres accomplies par les juristes de M\u00e9dine, car ils \u00e9taient ceux qui \u00e9taient les mieux inform\u00e9s au sujet des derni\u00e8res \u0153uvres h\u00e9rit\u00e9es du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) par les compagnons (qu\u2019Allah les agr\u00e9e).<\/p>\n<p style=\"text-align: justify;\">Il est certes authentifi\u00e9 par Boukhari dans son <strong><span class=\"tgras\">Sahih<\/span> <\/strong>et rapport\u00e9 par Malek dans son <strong><span class=\"tgras\">Mou-ata<\/span><\/strong> que les compagnons (qu\u2019Allah les agr\u00e9e) prenaient en compte les derni\u00e8res \u0153uvres accomplies par le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui). Or les \u0153uvres des juristes de M\u00e9dine sont ce qui \u00e9tait pr\u00e9sum\u00e9 \u00eatre les derni\u00e8res \u0153uvres accomplies par le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) et chez l\u2019Imam Malek la Sunna h\u00e9rit\u00e9e par les \u0153uvres est plus forte que celle h\u00e9rit\u00e9e par la parole.<\/p>\n<p style=\"text-align: justify;\">Il n\u2019y avait entre l\u2019Imam Malek et les compagnons (qu\u2019Allah les agr\u00e9e) qu\u2019un seul interm\u00e9diaire et ce sont les savants parmi les suivants qui ont \u00e9t\u00e9 t\u00e9moins des \u0153uvres des compagnons (qu\u2019Allah les agr\u00e9e) et qui l\u2019ont transmis \u00e0 ceux qui les pr\u00e9c\u00e9daient et parmi ceux-l\u00e0 se trouvaient l\u2019Imam Malek ibn Anas.<\/p>\n<p style=\"text-align: justify;\">Dans le <span class=\"tgras\">Majmou\u2019 Charh Madhheb<\/span> de l\u2019Imam Nawawi apr\u00e8s qu\u2019il ait \u00e9voqu\u00e9 dans l\u2019\u00e9cole des savants que le croisement des mains est une Sunna dans l\u2019\u00e9cole Chafi\u2019ite, que Ibn Moundher a \u00e9voqu\u00e9 que Abdallah ibn Zoube\u00efr, Hassan Basri et Nakha\u2019i (qu\u2019Allah les agr\u00e9e) allongeaient leur bras le long du corps et ils ne posaient point la main droite sur la gauche (posture du Qabdh) et qu\u2019il est rapport\u00e9 par le Qadi Abou Ta\u00efeb la m\u00eame chose \u00e0 propos d\u2019Ibn Sirrin, il a dit aussi que l\u2019imam Layth ibn Sa\u2019d allongeait ses bras et lorsqu\u2019il \u00e9tait fatigu\u00e9 il croisait ses bras pour se reposer. L\u2019allongement des bras est ce qui est le plus connu et c\u2019est \u00e0 quoi se sont conform\u00e9s les gens du Maghreb parmi les plus c\u00e9l\u00e8bres.<\/p>\n<p style=\"text-align: justify;\">Dans l\u2019\u00e9cole Malikite le croisement s\u2019effectue dans les pri\u00e8res sur\u00e9rogatoires comme il est prouv\u00e9 par le hadith de Wa-il ibn Hajr : <span class=\"paroles\">\u00ab <span style=\"color: #800000;\">[\u2026] vous montrerais-je comment j\u2019ai vu que le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) priait ?<\/span> \u00bb<\/span> et dans le hadith il posa sa main droite sur la main gauche et il est clair \u00e0 travers ce hadith que ce n\u2019\u00e9tait pas au cours d\u2019une pri\u00e8re obligatoire, sinon il serait rentr\u00e9 dans la pri\u00e8re avec lui.<\/p>\n<p style=\"text-align: justify;\">C\u2019est pour cela que l\u2019imam Malek (qu\u2019Allah l\u2019agr\u00e9e) a dit dans le <span class=\"tgras\"><strong>Moudawwana<\/strong> <\/span>: <span class=\"paroles\">\u00ab<span style=\"color: #800000;\"> Je ne connais pas cela concernant la pri\u00e8re obligatoire<\/span> \u00bb<\/span> et il n\u2019est pas sens\u00e9 que l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) ait pu voir ses ma\u00eetres prier en croisant leurs bras, posant la main droite sur la gauche au cours de la pri\u00e8re obligatoire et qu\u2019il aurait pourtant dit qu\u2019il ne conna\u00eet pas cet agissement chez ses ma\u00eetres. Il ne fait pas de doute que s\u2019ils avaient crois\u00e9 leurs bras, il les aurait certainement suivis.<\/p>\n<p style=\"text-align: justify;\">Cette affaire fait l\u2019unanimit\u00e9 chez les savants des \u00e9coles parmi les suivants, que chacun est dans la guid\u00e9e et que concernant les r\u00e8gles secondaires (Fourou\u2019) la forte pr\u00e9somption constitue un argument.<\/p>\n<p style=\"text-align: justify;\">Dans le <span class=\"tgras\"><strong>Mousannaf<\/strong> <\/span>d\u2019Ibn Abi Cha\u00efba, il a rapport\u00e9 d\u2019Abou Bakr qui a dit qu\u2019il a rapport\u00e9 de Haschim selon Younus selon Hassan et Moughira selon Ibrahim que tous deux allongeaient leur bras au cours de la pri\u00e8re.<\/p>\n<p style=\"text-align: justify;\">Il est rapport\u00e9 de \u2018Afan qui a dit qu\u2019il est rapport\u00e9 de Yazid ibn Ibrahim, il a dit : \u00ab <span style=\"color: #800000;\">J\u2019ai entendu \u2018Omar ibn Dinar dire : \u00ab <span class=\"paroles\">Ibn Zoube\u00efr lorsqu\u2019il priait il allongeait les bras.<\/span> <\/span>\u00bb Leurs cha\u00eenes de transmission proviennent toutes d\u2019hommes s\u00fbrs.<\/p>\n<p style=\"text-align: justify;\">Il est rapport\u00e9 par Yahiya ibn Sa\u2019id ibn Abdallah ibn \u2018Izar qui a dit : \u00ab <span style=\"color: #800000;\"><span class=\"paroles\">Je faisais le Tawwaf en compagnie de Sa\u2019id ibn Joubeyr lorsqu\u2019il a vu une personne priant avec une main pos\u00e9e sur l\u2019autre, il alla vers lui et s\u00e9para ses mains. <\/span>\u00bb<\/span> \u00bb <span class=\"tgras\">Fin de citation de Cheikh Hajj Makki Abdallah Tidjani.<\/span><\/p>\n<p style=\"text-align: justify;\">Le Docteur en hadith <span class=\"tgras\">Abdrahmane Taleb<\/span>, membre du haut conseil islamique d\u2019Alg\u00e9rie, a dit dans son \u00e9p\u00eetre intitul\u00e9e \u00ab le Qabdh et le Sadl sont tout deux des caract\u00e8res traditionnels de la pri\u00e8re \u00bb :<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>Premi\u00e8re question<\/strong><\/span> : \u00ab Est-il rapport\u00e9 des hadiths sur le fait de poser la main droite sur la gauche durant la pri\u00e8re ? \u00bb<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>R\u00e9ponse<\/strong><\/span> : \u00ab Oui, Sidi Mohamed El Mekki ibn \u2018Azzouz Tounsi \u00e0 dit dans son \u00e9p\u00eetre : \u00ab Il y a environ 20 hadiths \u00e0 ce sujet (Qabdh) qui proviennent d\u2019environ 18 compagnons (qu\u2019Allah les agr\u00e9e), la plupart sont valides (Sahih) et bon (Hassan) et ceux qui n\u2019atteignent pas ce degr\u00e9 sont \u00e9lev\u00e9s par le soutien de leur conformit\u00e9 \u00bb.<\/p>\n<p style=\"text-align: justify;\">Mais en fait Cheikh Mohamed \u2018Abid ibn Cheikh Housse\u00efni, le Mufti mal\u00e9kite de La Mecque a r\u00e9pliqu\u00e9 par son \u00e9crit intitul\u00e9 \u00ab La parole tranchante sur la consolidation de la tradition de l\u2019allongement des bras \u00bb dans lequel tous les arguments et les r\u00e9f\u00e9rences ont \u00e9t\u00e9 m\u00e9ticuleusement d\u00e9cortiqu\u00e9s, et en conclusion concernant le caract\u00e8re valide de la plupart des hadiths sur le fait d\u2019empoigner les bras (Qabdh), il dit :<\/p>\n<p style=\"text-align: justify;\">\u00ab En r\u00e9alit\u00e9 le Qabdh n\u2019a pas \u00e9t\u00e9 rapport\u00e9 selon des voies valides, il n\u2019y a pas ce qu\u2019il pr\u00e9tend, la seule voie valide est celle de Sahl ibn Sa\u2019d (qu\u2019Allah l\u2019agr\u00e9e) qui est rapport\u00e9 dans le <span class=\"tgras\">Moua-ta<\/span> (de l\u2019Imam Malik), ainsi que Boukhari et Mouslim et l\u2019\u00e9nonc\u00e9 du hadith avec sa cha\u00eene est la suivante : Il est rapport\u00e9 par Abdallah ibn Maslama selon Malik selon Abou Hazm selon Sahl ibn Sa\u2019d (qu\u2019Allah les agr\u00e9e) qui a dit : \u00ab <span class=\"paroles\">Les gens ordonnaient que la personne pose la main droite sur le poignet gauche pendant la pri\u00e8re<\/span> \u00bb. Ibn Hazm a dit : <span class=\"paroles\">\u00ab Je ne sais pas s\u2019ils rattachent cela au Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) \u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\">Le Mufti malikite a dit : \u00ab En r\u00e9sum\u00e9 les hadiths traitant du Qabdh ne sont donc ni en majorit\u00e9 valides, ni m\u00eame de la cat\u00e9gorie des bons (Hassan) ni ne sont exempts de faiblesse, mais ils varient entre les hadiths fix\u00e9s \u00e0 un compagnon (<span class=\"tgras\">Maouqouf<\/span>), entre l\u2019instable (<span class=\"tgras\">Moudtarib<\/span>) et le faible (<span class=\"tgras\">Da\u2019if<\/span>) comme vous avez pu le constater \u00bb.<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>Deuxi\u00e8me question<\/strong><\/span> : L\u2019aspect traditionnel du Qabdh est \u00e9tabli par des hadiths divergeant quant \u00e0 leur degr\u00e9, mais existe-t-il des hadiths qui montrent l\u2019aspect traditionnel (Sunna) de l\u2019allongement des bras (Sadl) ?<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>R\u00e9ponse<\/strong> <\/span>: \u00ab Oui, il y a des hadiths valides qui ne sont pas touch\u00e9s par le caract\u00e8re instable et faible que l\u2019on retrouve dans les voies de transmission des hadiths sur le Qabdh. Le premier hadith est celui sur la personne qui a mal fait sa pri\u00e8re : Ibn Battal a dit dans son commentaire de Boukhari :<\/p>\n<p style=\"text-align: justify;\">\u00ab L\u2019argument de ceux qui r\u00e9prouvent (Makrouh) le Qabdh est que le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) a enseign\u00e9 la pri\u00e8re \u00e0 quelqu\u2019un qui l\u2019avait mal fa\u00eete et il n\u2019a pas mentionn\u00e9 la posture du Qabdh, le hadith est le suivant :<\/p>\n<p style=\"text-align: justify;\">\u00ab El Hakem a rapport\u00e9 dans <span class=\"tgras\">El Moustadrak<\/span> selon une cha\u00eene valide selon le compagnon Rabi\u2019a ibn Rafi\u2019 (qu\u2019Allah l\u2019agr\u00e9e) qui \u00e9tait assis aupr\u00e8s du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) lorsqu\u2019un homme entra dans la mosqu\u00e9e et pria. Quand il a fini sa pri\u00e8re, il vint saluer le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) et le groupe.<\/p>\n<p style=\"text-align: justify;\">Le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) lui a dit : <span class=\"hadith\">\u00ab <span style=\"color: #800000;\"><strong>Ainsi qu\u2019\u00e0 toi. Retourne, va prier, car tu n\u2019as pas pri\u00e9<\/strong><\/span> \u00bb. <\/span>Il dit : \u00ab Il retourna donc et nous regardions sa pri\u00e8re sans savoir ce qui l\u2019avait rendue d\u00e9fectueuse. Lorsqu\u2019il a fini sa pri\u00e8re, il vint, salua le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) et le groupe et alors le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) lui a dit : <span class=\"hadith\">\u00ab<strong><span style=\"color: #800000;\"> Retourne, car tu n\u2019as pas pri\u00e9<\/span> <\/strong>\u00bb<\/span> et il a \u00e9voqu\u00e9 cela deux ou trois fois. L\u2019homme lui demanda : \u00ab Je ne sais pas ce qui a rendu ma pri\u00e8re d\u00e9fectueuse \u00bb.<\/p>\n<p style=\"text-align: justify;\">Le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) dit alors :<\/p>\n<p style=\"text-align: justify;\"><span class=\"hadith\">\u00ab <span style=\"color: #800000;\"><strong>L\u2019un d\u2019entre vous ne peut parfaire sa pri\u00e8re tant qu\u2019il n\u2019a pas accompli les ablutions tel que l\u2019a ordonn\u00e9 Allah. Il lave son visage et ses mains jusqu\u2019aux coudes, il essuie sa t\u00eate avec ses mains et ses pieds jusqu\u2019aux chevilles. <\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong><span class=\"hadith\">Ensuite il prononce la formule de Takbir (dire : Allahou Akbar) louange Allah et le glorifie et il r\u00e9cite du Qoran ce qu\u2019Allah lui permet, ensuite il prononce le Takbir et s\u2019incline en posant la paume de ses mains sur ses genoux jusqu\u2019\u00e0 ce qu\u2019il immobilise tranquillement ses membres et se maintienne droit. <\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong><span class=\"hadith\">Ensuite il se rel\u00e8ve en disant : \u00ab Dieu entend celui qui le loue \u00bb et il reste debout ainsi jusqu\u2019\u00e0 ce que ses articulations retrouvent leurs places. Ensuite il reste bien droit et il prononce le Takbir en se prosternant. Il laisse son front en prosternation jusqu\u2019\u00e0 immobiliser tranquillement chacun de ses membres en restant droit. <\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong><span class=\"hadith\">Ensuite il prononce le Takbir et rel\u00e8ve sa t\u00eate prenant une position assise jusqu\u2019\u00e0 ce que ses membres s\u2019immobilisent tranquillement et reste droit \u00bb<\/span>. Il d\u00e9crivit ainsi de suite la pri\u00e8re jusqu\u2019\u00e0 la finir ensuite il dit (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) : <\/strong><\/span><span class=\"hadith\"><span style=\"color: #800000;\"><strong>\u00ab La pri\u00e8re d\u2019une personne ne peut \u00eatre compl\u00e8te que s\u2019il l\u2019accomplit ainsi<\/strong> <\/span>\u00bb<\/span>. El Hakem a dit que ce hadith est valide (Sahih) selon les crit\u00e8res de Boukhari et Mouslim en d\u00e9finissant sa voie de transmission.<\/p>\n<p style=\"text-align: justify;\">C\u2019est pour cela, et Allah est le plus savant, que l\u2019Imam Ibn Qassar a argument\u00e9 au sujet du Sadl suivi par Ibn Battal, car le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) a enseign\u00e9 \u00e0 celui qui a mal fat sa pri\u00e8re sans lui \u00e9voquer la posture du Qabdh alors que par l\u00e0 m\u00eame il lui mentionna les actes traditionnels et m\u00e9ritoires. Comment se pourrait-il que le Qabdh soit un aspect traditionnel (Sunna) si le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) ne le lui enseigne point alors qu\u2019il lui inculque pourtant les actes traditionnels de la pri\u00e8re.<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\"><strong>Remarque<\/strong> <\/span>: Il existe deux versions de ce hadith et deux aspects : La premi\u00e8re est celle que nous venons de voir et la seconde selon la version d\u2019Abou Houreyra (qu\u2019Allah l\u2019agr\u00e9e) ne mentionne que les actes obligatoires sans \u00e9voquer les actes traditionnels, c\u2019est d\u2019ailleurs \u00e0 cause de ce hadith que Zine El \u2018Iraqi, le Cheikh d\u2019Ibn El Hajj, avait dit dans le commentaire de Tirmidhi : <span class=\"paroles\">\u00ab<span style=\"color: #800000;\"> Il n\u2019y a pas de preuve dans le hadith de celui qui a mal fa\u00eete sa pri\u00e8re qui permette de justifier le caract\u00e8re non souhaitable (Makrouh) de la pose de la main droite sur la gauche durant la pri\u00e8re, car le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) n\u2019a mentionn\u00e9 que les actes obligatoires pour que ce soit plus facile \u00e0 retenir sans ne mentionner aucun acte traditionnel (Sunna).<\/span> \u00bb<\/span><\/p>\n<p style=\"text-align: justify;\">Cheikh Mohamed \u2018Abid, le Mufti malikite de La Mecque, pr\u00e9cisa : <span class=\"paroles\">\u00ab <span style=\"color: #800000;\">Il ne fait pas de doute que si El Iraqi l\u2019avait vu ou s\u2019en \u00e9tait rappel\u00e9, il aurait alors reconnu qu\u2019il y a effectivement une preuve, car dans cette version il y est bien mentionn\u00e9 les actes traditionnels (Sunna) comme m\u00e9ritoires et autres<\/span> \u00bb<\/span>. Fin de la remarque.<\/p>\n<p style=\"text-align: justify;\">Parmi les actes traditionnels qui sont \u00e9voqu\u00e9s dans ce hadith il y a : poser les paumes des mains sur les genoux, les Takbir (autre que le premier), le Tasbih, la formule : \u00ab Dieu entend celui qui le loue \u00bb dans l\u2019inclinaison, se relever de l\u2019inclinaison\u2026<\/p>\n<p style=\"text-align: justify;\">Le deuxi\u00e8me hadith est celui du compagnon nomm\u00e9 Abou Houme\u00efd Sa\u2019di (qu\u2019Allah l\u2019agr\u00e9e) qu\u2019\u00e0 rapport\u00e9 Boukhari dans le Sahih ainsi que Nassa-i, Abou Daoud et d\u2019autres qu\u2019eux. L\u2019\u00e9nonc\u00e9 d\u2019Abou Daoud est le suivant :<\/p>\n<p style=\"text-align: justify;\">\u00ab Misded nous a rapport\u00e9 selon Yahiya selon Mohamed ibn \u2018Omar (qu\u2019Allah l\u2019agr\u00e9e) selon \u2018Ata-a qui a dit : <span class=\"paroles\">\u00ab <span style=\"color: #800000;\">J\u2019ai entendu Abou Houme\u00efd Sa\u2019di (qu\u2019Allah l\u2019agr\u00e9e) dire en pr\u00e9sence des compagnons et parmi eux se trouvaient Abou Qatada (dans une autre version : ainsi qu\u2019Abou Houreyra et Mohamed ibn Maslama et Sahl ibn Sa\u2019d (qu\u2019Allah les agr\u00e9e) et d\u2019autre qu\u2019eux) : \u00ab Je suis mieux inform\u00e9 que vous sur la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) \u00bb. Ils lui demand\u00e8rent : \u00ab Et pourquoi donc ? Tu ne le suivais pas mieux que nous et tu ne lui as pas tenu compagnie plus que nous, montre voir \u00bb.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\">Il leur montra en disant : <span class=\"paroles\">\u00ab Le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) lorsqu\u2019il se levait pour accomplir la pri\u00e8re il levait ses mains jusqu\u2019\u00e0 hauteur des \u00e9paules ensuite il pronon\u00e7ait le Takbir et il stabilisait chaque membre \u00e0 sa place de fa\u00e7on pond\u00e9r\u00e9e, ensuite il r\u00e9citait, puis il pronon\u00e7ait le Takbir et levait les mains jusqu\u2019\u00e0 hauteur des \u00e9paules de fa\u00e7on pond\u00e9r\u00e9e et il s\u2019inclinait en posant ses paumes sur ses genoux et il restait un temps \u00e9quivalent, ni il baissait ni il levait sa t\u00eate. <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\"><span style=\"color: #800000;\">Ensuite il levait sa t\u00eate en disant : \u00ab Dieu entend celui qui le loue \u00bb, ensuite il levait ses mains jusqu\u2019\u00e0 hauteur des \u00e9paules de fa\u00e7on pond\u00e9r\u00e9 ensuite il pronon\u00e7ait le Takbir et tombait \u00e0 terre en posant ses mains de chaque c\u00f4t\u00e9, ensuite il relevait sa t\u00eate en pliant le pied gauche et en s\u2019asseyant dessus et il rel\u00e2chait les orteils lorsqu\u2019il se prosternait, ensuite il pronon\u00e7ait le Takbir et se relevait en pliant le pied gauche et s\u2019asseyant dessus et il stabilisait chaque membre \u00e0 sa place ensuite il fait la m\u00eame chose avec l\u2019autre, ensuite il se rel\u00e8ve de ses deux cycles de pri\u00e8re (Rak\u2019a) puis prononce le Takbir et il l\u00e8ve ses mains \u00e0 hauteur des \u00e9paules tout comme il l\u2019avait fait au commencement de sa pri\u00e8re et il agit ainsi tout le restant de sa pri\u00e8re jusqu\u2019au<\/span> moment<span style=\"color: #800000;\"> o\u00f9 il se retrouve assis dans la position de la salutation o\u00f9 il recule alors son pied gauche en s\u2019appuyant sur son flanc gauche \u00bb. Tous lui dirent alors : \u00ab Tu as parfaitement raison, c\u2019est ainsi qu\u2019il priait \u00bb<\/span>. <\/span><\/p>\n<p style=\"text-align: justify;\">Ce hadith a \u00e9t\u00e9 rapport\u00e9 par Ibn Hanbal et comme on peut le constater il s\u2019agit d\u2019une preuve probante concernant l\u2019allongement des bras (Sadl) car Abou Houme\u00efd (qu\u2019Allah l\u2019agr\u00e9e) l\u2019a utilis\u00e9 comme argument devant la contestation des compagnons (qu\u2019Allah les agr\u00e9e) lorsqu\u2019il leur a affirm\u00e9 : \u00ab <span style=\"color: #800000;\">Je suis mieux inform\u00e9 que vous de la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui)<\/span> \u00bb et qu\u2019ils ne lui c\u00e9d\u00e8rent point ce fait, lui objectant : \u00ab <span style=\"color: #800000;\">[\u2026] tu ne le suivais pas mieux que nous\u2026<\/span> \u00bb<\/p>\n<p style=\"text-align: justify;\">Ainsi, ils ne s\u2019inclin\u00e8rent que lorsqu\u2019il leur d\u00e9crivit avec pr\u00e9cision la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) avec les actes traditionnels (Sunna) et obligatoires (Fard) sans rien \u00e9pargner de ce qu\u2019il savait. C\u2019est alors qu\u2019ils lui d\u00e9clar\u00e8rent : \u00ab <span style=\"color: #800000;\">Tu as parfaitement raison<\/span> \u00bb et ils lui conc\u00e9d\u00e8rent sa pr\u00e9tention.<\/p>\n<p style=\"text-align: justify;\">Par cons\u00e9quent, si le Qabdh faisait partie des caract\u00e9ristiques de la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) alors les compagnons (qu\u2019Allah les agr\u00e9e) n\u2019auraient pas manqu\u00e9 d\u2019objecter en lui disant : \u00ab \u00d4 Abou Houme\u00efd, tu n\u2019as pas accompli (ou tu as oubli\u00e9) le fait de tenir ta gauche par ta droite \u00bb, car cela leur aurait fourni un argument en leur faveur dans ce contentieux o\u00f9 ils n\u2019auraient laiss\u00e9 passer aucune lacune.<\/p>\n<p style=\"text-align: justify;\">Or du fait justement qu\u2019ils n\u2019ont rien contest\u00e9, c\u2019est qu\u2019ils furent unanimes sur le d\u00e9laissement du Qabdh dans la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) et qu\u2019il priait donc avec les bras allong\u00e9s (Sadl) car tel \u00e9tait le fondement et le fondement n\u2019a pas besoin d\u2019\u00eatre \u00e9voqu\u00e9 et s\u2019y conformer c\u2019est se conformer \u00e0 ce qui a \u00e9t\u00e9 statu\u00e9 par l\u2019unanimit\u00e9.<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>Troisi\u00e8me question<\/strong><\/span> : Existe t-il \u00e0 ce sujet de quoi expliquer et consolider le Hadith de Rifa\u2019at et de Abou Houme\u00efd ?<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>R\u00e9ponse<\/strong> <\/span>: Oui, en effet en ce qui concerne l\u2019explication du hadith de Rifa\u2019at et celui de Houme\u00efd et de ses compagnons, le savant Mohamed \u2018Abid, Mufti malikite, a dit : \u00ab Il est rapport\u00e9 de Tabarani dans son <span class=\"tgras\">Mou\u2019jam El Kabir<\/span> selon Mahboub ibn El Hasan ainsi qu\u2019El Khatib ibn Jahdar selon Mou\u2019adh ibn Jabal (qu\u2019Allah l\u2019agr\u00e9e) qui a dit :<\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\">\u00ab <span style=\"color: #800000;\">Lorsque le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) se levait pour prier, il levait ses mains au niveau des oreilles et il pronon\u00e7ait le Takbir puis ils les allongeaient, ensuite il se taisait<\/span> \u00bb. <\/span>Dans une autre version<span class=\"paroles\"> : \u00ab<span style=\"color: #800000;\"> [\u2026] et parfois il tenait l\u2019une par l\u2019autre<\/span> \u00bb<\/span>.<\/p>\n<p style=\"text-align: justify;\">Comme on peut l\u2019observer, ce hadith peut \u00eatre utilis\u00e9 afin d\u2019expliquer et de soutenir les deux hadiths pr\u00e9c\u00e9dents et il permet aussi de d\u00e9nouer le n\u0153ud du probl\u00e8me et de mettre fin aux ou\u00ef-dire. En effet, le hadith de Mou\u2019adh ibn Jabal (qu\u2019Allah l\u2019agr\u00e9e) laisse parfaitement entrevoir que le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) a accompli les deux postures. De ce fait, au moment o\u00f9 il a fait le Qabdh certains l\u2019ont vu et l\u2019ont alors rapport\u00e9 ainsi, et au moment o\u00f9 il a fait le Sadl certains l\u2019ont vu et ils n\u2019ont donc pas rapport\u00e9 qu\u2019il faisait le Qabdh. Par cons\u00e9quent, chacun l\u2019a rapport\u00e9 selon une version et chaque Imam a ainsi sa preuve et chacun sait o\u00f9 s\u2019abreuver.<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>Quatri\u00e8me question<\/strong><\/span> : Y a-t-il parmi les grands Imams ceux qui d\u00e9clarent l\u2019aspect traditionnel (Sunna) du Sadl ?<\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>R\u00e9ponse<\/strong> <\/span>: Le Mufti malikite a dit ; \u00ab Constatons donc :<\/p>\n<p style=\"text-align: justify;\"><strong><span class=\"tgras\">(1)<\/span><\/strong> L\u2019Imam Ibn Qassar et, \u00e0 sa suite, Ibn Battal qui ont soutenu le Sadl en consid\u00e9ration du hadith de celui qui a mal fait sa pri\u00e8re rapport\u00e9 par Rifa\u2019at. De plus, l\u2019Imam Ibn Battal a dit dans le commentaire de Boukhari que les savants ont diverg\u00e9 sur ce point, c\u2019est \u00e0 dire au sujet de tenir une main par une autre. Certains l\u2019ayant consid\u00e9r\u00e9 comme acte m\u00e9ritoire (<span class=\"tgras\">Moustahab<\/span>) alors que d\u2019autres pr\u00e9f\u00e8rent l\u2019allongement des bras (Sadl), cela a \u00e9t\u00e9 rapport\u00e9 par Abdallah ibn Zoube\u00efr (qu\u2019Allah l\u2019agr\u00e9e).<\/p>\n<p style=\"text-align: justify;\"><strong><span class=\"tgras\">(2)<\/span><\/strong> Il y a aussi ce qu\u2019a rapport\u00e9 Ibn El Qacem sur l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) dans <span class=\"tgras\">El Moudawwana<\/span> au sujet du fait de tenir sa gauche par sa main droite dans la pri\u00e8re, il dit : <span class=\"paroles\">\u00ab Je ne connais pas cette pratique dans la pri\u00e8re obligatoire, mais dans la pri\u00e8re sur\u00e9rogatoire si elle se prolonge il n\u2019y a pas de mal \u00e0 le faire si c\u2019est pour s\u2019aider \u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\">La parole de l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) qui dit : <span class=\"paroles\">\u00ab Je ne connais pas cette pratique [\u2026] \u00bb<\/span> c\u2019est-\u00e0-dire que le Qabdh n\u2019\u00e9tait pas pratiqu\u00e9 dans la pri\u00e8re par ses ma\u00eetres parmi les g\u00e9n\u00e9rations des suivants (Tabi\u2019in) et ceux qui leur ont succ\u00e9d\u00e9 tel que le c\u00e9l\u00e8bre Sa\u00efd ibn El Moussayeb (qu\u2019Allah l\u2019agr\u00e9e) qui fait partie des sept plus \u00e9minents juristes de M\u00e9dine et de m\u00eame concernant Hassan Basri (qu\u2019Allah l\u2019agr\u00e9e), Ibn Sirrin et Ibn Joube\u00efr, qui eux, ont c\u00f4toy\u00e9 les compagnons (qu\u2019Allah les agr\u00e9e).<\/p>\n<p style=\"text-align: justify;\">L\u2019ensemble des musulmans est unanime pour affirmer que ceux-l\u00e0 \u00e9taient particularis\u00e9s par leur scrupule, leur asc\u00e9tisme et leur crainte qui \u00e9tait telle qu\u2019il leur \u00e9tait impossible de diverger avec les compagnons (qu\u2019Allah les agr\u00e9e) que ce soit dans la parole ou dans les actes.<\/p>\n<p style=\"text-align: justify;\"><strong><span class=\"tgras\">(3)<\/span><\/strong> L\u2019Imam Ibn Rouchd a dit : \u00ab Les savants ont diverg\u00e9 au sujet de la posture consistant \u00e0 poser la main droite sur la gauche pendant la pri\u00e8re. L\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) a d\u00e9clar\u00e9 que cela est non souhaitable (Makrouh) dans les pri\u00e8res obligatoires, le permettant pour les sur\u00e9rogatoires. D\u2019autres sont regroup\u00e9s pour dire que cela fait partie des actes traditionnels de la pri\u00e8re.<\/p>\n<p style=\"text-align: justify;\">La cause de cette divergence est qu\u2019il y a des actes attribu\u00e9s aux compagnons (<span class=\"tgras\">Athar<\/span>) qui sont \u00e9tablis et dans lesquels il est mentionn\u00e9 les caract\u00e9ristiques de la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui). Or il n\u2019est point mentionn\u00e9 justement qu\u2019il posait sa main droite sur la gauche, mais d\u2019autre part il est mentionn\u00e9 que les gens ordonnaient de la faire. Il est rapport\u00e9 aussi que cela fait partie des caract\u00e9ristiques de la pri\u00e8re du Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui).<\/p>\n<p style=\"text-align: justify;\">D\u2019autres savants ont sp\u00e9cifi\u00e9 que les deux postures sont \u00e9tablies par la Loi, tel Ibn AbdelBarr El Maliki dans son livre <span class=\"tgras\">El Kafi<\/span> qui a dit que toutes deux, que ce soit le Qabdh ou le Sadl font partie de la Sunna. El Amir a dit dans son \u00e9p\u00eetre <span class=\"tgras\">Kaoukeb El Mounir<\/span> : <span class=\"paroles\">\u00ab L\u2019affaire concernant le Qabdh des deux mains ou leur allongement est libre \u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>Cinqui\u00e8me question<\/strong><\/span> : Comment donc concilier le fait que l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) a retranscrit le hadith sur le Qabdh dans son <span class=\"tgras\">Moua-ta<\/span> alors qu\u2019il d\u00e9clare son caract\u00e8re non souhaitable dans le <span class=\"tgras\">Moudawwana<\/span> ? C\u2019est \u00e0 dire entre ce hadith : <span class=\"paroles\">\u00ab Les gens ordonnaient aux personnes de poser la main droite sur le poignet gauche pendant la pri\u00e8re \u00bb Ibn Hazm a dit : \u00ab Je ne sais pas s\u2019ils rattachent cela au Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) \u00bb <\/span>et entre la parole dans <span class=\"tgras\">El Moudawwana<\/span> rapport\u00e9 par Ibn El Qacem : <span class=\"paroles\">\u00ab Je ne connais pas cette pratique dans la pri\u00e8re obligatoire \u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"tgras\">&#8211; <strong>R\u00e9ponse<\/strong><\/span> : Le Mufti malikite a dit, rapportant des savants en hadith (Mouhadithine), que celui d\u2019entre eux qui rapporte un hadith, mais qui affirme pourtant le contraire de ce qu\u2019il a rapport\u00e9 cela est pour sp\u00e9cifier le caract\u00e8re abrog\u00e9 (Mansoukh) du hadith rapport\u00e9 et c\u2019est de cette d\u00e9marche que r\u00e9sulte ce cas.<\/p>\n<p style=\"text-align: justify;\">Le hadith sur le Qabdh, celui qui est rapport\u00e9 selon Sahl (qu\u2019Allah l\u2019agr\u00e9e), est retranscrit dans le <span class=\"tgras\">Moua-ta<\/span> par l\u2019Imam Malek (qu\u2019Allah l\u2019agr\u00e9e) et c\u2019est de lui que ce hadith a \u00e9t\u00e9 repris par Boukhari et Mouslim, et donc avec cela il a mentionn\u00e9 le fait de son caract\u00e8re non souhaitable (Makrouh) dans <span class=\"tgras\">El Moudawwana<\/span> et du caract\u00e8re recommand\u00e9 (Moustahab) du Sadl. Or le <span class=\"tgras\">Moudawwana<\/span> dans sa r\u00e9daction est post\u00e9rieur au <span class=\"tgras\">Moua-ta<\/span> et il est \u00e9tabli pour traiter des r\u00e8gles de jurisprudence contrairement au <span class=\"tgras\">Moua-ta<\/span> qui traite seulement des hadiths. Quant \u00e0 sa parole : <span class=\"paroles\">\u00ab Je ne connais pas cette pratique [\u2026] \u00bb<\/span> comme il est rapport\u00e9 dans <span class=\"tgras\">El Moudawwana<\/span> : \u00ab L\u2019Imam consid\u00e8re le Qabdh comme non souhaitable dans les pri\u00e8res obligatoires, il a dit : \u00ab Je ne connais pas cette pratique dans les pri\u00e8res obligatoires \u00bb.<\/p>\n<p style=\"text-align: justify;\">Il est tr\u00e8s clair que les gens de M\u00e9dine ne le pratiquaient pas ainsi, donc sa parole \u00ab Je ne connais pas cette pratique [\u2026] \u00bb veut dire \u00ab Je ne connais pas cette pratique chez les actes des Imams parmi la g\u00e9n\u00e9ration des Suivants (Tabi\u2019ine) qui ont pour leur part recueilli leurs sciences des compagnons (qu\u2019Allah les agr\u00e9e) \u00bb. Or \u00e9tant donn\u00e9 d\u2019une part que le hadith sur le Qabdh est rapport\u00e9 par lui et que c\u2019est de lui qu\u2019il a \u00e9t\u00e9 rapport\u00e9 par les deux Cheikh (Boukhari et Mouslim) et que d\u2019autre part avec cela il a dit : <span class=\"paroles\">\u00ab Je ne connais pas cette pratique [\u2026] \u00bb,<\/span> cela montre in\u00e9luctablement le caract\u00e8re abrog\u00e9 du Qabdh \u00bb. F<span class=\"tgras\">in de citation du Docteur <\/span><span class=\"tgras\">Taleb Abdrahmane<\/span>.<\/p>\n<p style=\"text-align: justify;\">En conclusion, la posture du <span class=\"tgras\">Qabdh<\/span> et du <span class=\"tgras\">Sadl<\/span> entre dans le domaine des sciences d\u00e9riv\u00e9es (<span class=\"tgras\">Fourou\u2019<\/span>) de la Loi et comme il est connu il n\u2019est pas permis de critiquer l\u2019une ou l\u2019autre posture, car chacune a ses preuves et ses arguments. Ainsi, chacun choisit ce qui lui semble le plus convenable et toutes deux font bel et bien partie de la Sunna proph\u00e9tique, mais en aucun cas il est permis de dire cela est la Sunna et cela ne l\u2019est pas, car tel est la source de l\u2019ignorance et de l\u2019intol\u00e9rance qui ne sied point \u00e0 cette noble religion.<\/p>\n<p style=\"text-align: justify;\"><strong>Zaouiya Tidjaniya El Koubra d\u2019Europe<\/strong><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pourriez-vous me renseigner au sujet de la posture des bras crois\u00e9es (qabdh) ou allong\u00e9es (Sadl) au cours de la pri\u00e8re ? Est-ce vrai que la posture allong\u00e9e n&rsquo;a aucun fondement dans la Sunna ?<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-305","post","type-post","status-publish","format-standard","hentry","category-faq-general"],"blocksy_meta":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":""},"post_excerpt_stackable_v2":"<p>Pourriez-vous me renseigner au sujet de la posture des bras crois\u00e9es (qabdh) ou allong\u00e9es (Sadl) au cours de la pri\u00e8re ? Est-ce vrai que la posture allong\u00e9e n&rsquo;a aucun fondement dans la Sunna ? REPONSE Le savant et Cheikh Hajj Makki Abdallah Tidjani a dit : \u00ab Certains \u00e9tudiants en science d\u2019ob\u00e9dience Wahhabites disent et pr\u00e9tendent que les Malikites allongent les bras le long du corps pendant la pri\u00e8re sans avoir aucune preuve, alors que le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui) croisait les bras pendant la pri\u00e8re et il y a des hadiths authentiques\u2026<\/p>\n","category_list_v2":"<a href=\"https:\/\/tidjaniya.com\/fr\/category\/faq-general\/\" rel=\"category tag\">Vos questions<\/a>","author_info_v2":{"name":"Samia Ajdid","url":"https:\/\/tidjaniya.com\/fr\/author\/samia-ajdid\/"},"comments_num_v2":"0 commentaire","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Samia Ajdid","author_link":"https:\/\/tidjaniya.com\/fr\/author\/samia-ajdid\/"},"uagb_comment_info":0,"uagb_excerpt":"Pourriez-vous me renseigner au sujet de la posture des bras crois\u00e9es (qabdh) ou allong\u00e9es (Sadl) au cours de la pri\u00e8re ? Est-ce vrai que la posture allong\u00e9e n&rsquo;a aucun fondement dans la Sunna ?","_links":{"self":[{"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/posts\/305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/comments?post=305"}],"version-history":[{"count":0,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/posts\/305\/revisions"}],"wp:attachment":[{"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/media?parent=305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/categories?post=305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/tags?post=305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}