{"id":95,"date":"2018-07-11T12:37:52","date_gmt":"2018-07-11T10:37:52","guid":{"rendered":"https:\/\/tidjaniya.com\/fr\/?p=95"},"modified":"2018-07-11T12:37:52","modified_gmt":"2018-07-11T10:37:52","slug":"lallah-mannana-qu-allah-l-agree","status":"publish","type":"post","link":"https:\/\/tidjaniya.com\/fr\/lallah-mannana-qu-allah-l-agree\/","title":{"rendered":"Lallah Mannana, qu&rsquo;ALLAH l&rsquo;agr\u00e9e"},"content":{"rendered":"<div class=\"content-text\">\n<p style=\"text-align: justify;\">La majdhouba (attir\u00e9e par Allah) connue Lalla Mannana. Elle fut (qu\u2019Allah lui accorde mis\u00e9ricorde), de ceux dont les pieds \u00e9taient enracin\u00e9s dans le d\u00e9voilement (Moukachafa) et son \u00e9tat de ravissement (Jadhb) prenait le dessus sur elle \u00e0 certains moments.<\/p>\n<p style=\"text-align: justify;\">Souvent, elle se rendait chez Sidi Ahmed ibn Mohamed El Banani (qu\u2019Allah l\u2019agr\u00e9e). Lorsque celui-ci alla chez elle afin de la consulter sur son d\u00e9sir d\u2019entrer dans la Tariqa, elle l&rsquo;accueillit avec hospitalit\u00e9 puis lui conseilla de s&#8217;empresser de prendre la Tariqa de Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret). Elle lui raconta ses m\u00e9rites et ce qu\u2019elle a v\u00e9cu avec lui.<\/p>\n<p style=\"text-align: justify;\">Il a \u00e9t\u00e9 racont\u00e9 que lorsque Sidi Banani (qu\u2019Allah l\u2019agr\u00e9e) voulut la consulter dans son affaire, elle lui dit, avant m\u00eame qu\u2019il ne parle ne serait-ce qu&rsquo;un mot\u00a0:<\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\">\u00ab\u00a0<span style=\"color: #800000;\">\u00d4 Sidi Ahmed\u00a0! Tu es venu afin de me consulter au sujet de ton engagement dans la voie de Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret), si tu acceptes mon conseil empresse-toi de te soumettre \u00e0 lui, il est certainement le Sultan. Il m&rsquo;est arriv\u00e9, dit-elle, avec Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) des \u00e9v\u00e8nements et je t\u2019en cite un\u00a0:<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\"><span style=\"color: #800000;\">Un jour o\u00f9 j&rsquo;\u00e9tais assise chez moi, il m\u2019est venu deux personnes qui m\u2019ont dit\u00a0: \u00ab\u00a0L\u00e8ve-toi afin de parler au Sultan\u00a0\u00bb, je pensais alors qu\u2019il s&rsquo;agissait du Sultan Soule\u00efman<\/span>\u00a0\u00bb<\/span>.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">En effet, celui-ci lui envoyait souvent des messages et de m\u00eame elle allait souvent le voir, il l&rsquo;affectionnait particuli\u00e8rement. Elle continue\u00a0:<\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\">\u00ab\u00a0<span style=\"color: #800000;\">Je suis donc all\u00e9e avec eux jusqu\u2019\u00e0 notre arriv\u00e9e \u00e0 la porte d\u2019El Ftouh (une des portes de F\u00e8s). Je me suis avanc\u00e9e vers le Sultan et je constatais que ce n\u2019\u00e9tait pas Maoulana Soule\u00efman, mais c&rsquo;\u00e9tait Se\u00efdina Ahmed Tidjani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) et je ne le connaissais pas auparavant.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\"><span style=\"color: #800000;\">Puis le Sultan Sidi Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) me demanda\u00a0: <span class=\"saidina\">\u00ab\u00a0Que penses-tu au sujet de la peste qui a envahi la ville\u00a0? Certainement, il ne pouvait que l&rsquo;envahir vu cette cat\u00e9gorie de gens qui se caract\u00e9rise par tel et tel fait\u00a0\u00bb<\/span> et il cita un ensemble d&rsquo;agissements<\/span>\u00a0\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\">Sidi Ahmed Banani (qu\u2019Allah l\u2019agr\u00e9e) continu de raconter\u00a0:<\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\">\u00ab\u00a0<span style=\"color: #800000;\">Lorsqu&rsquo;elle entendit cela de sa part, elle lui r\u00e9pondit\u00a0: \u00ab\u00a0Si tous les saints existants n&rsquo;ont pas pu faire face \u00e0 ce malheur je suis capable de lever cette calamit\u00e9 des gens\u00a0\u00bb. Il me dit\u00a0: <span class=\"saidina\">\u00ab\u00a0Es-tu capable de supporter cela et de l&rsquo;endurer\u00a0?\u00a0\u00bb<\/span> Elle dit\u00a0: \u00ab\u00a0Oui\u00a0\u00bb.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\"><span style=\"color: #800000;\">Il lui ordonna donc de retourner \u00e0 sa demeure et lorsqu&rsquo;elle rentra par la porte de la ville elle entendit derri\u00e8re elle comme une d\u00e9flagration qui l&rsquo;avait atteinte. Elle tomba sur son visage et resta ainsi jusqu\u2019\u00e0 ce que les gens la transportent chez elle. Ceux-ci entendirent le son de la d\u00e9flagration retentir en elle et, dans cet \u00e9tat, elle criait \u00e0 chaque fois jusqu&rsquo;\u00e0 ce qu&rsquo;Allah d\u00e9cr\u00e8te l&rsquo;\u00e9l\u00e9vation de cette calamit\u00e9 sur la ville\u00a0<\/span>\u00bb<\/span>.<\/p>\n<p style=\"text-align: justify;\">Parmi les \u00e9v\u00e8nements qui lui sont arriv\u00e9s, il y a \u00e9galement qu&rsquo;au cours de certaines ann\u00e9es, les Majadhib (pluriel de Majdhoub) parl\u00e8rent souvent des calamit\u00e9s, des \u00e9preuves et des changements de situation qui allaient survenir. Sidi Banani (qu\u2019Allah l\u2019agr\u00e9e), apr\u00e8s avoir su que la situation \u00e9tait tr\u00e8s grave, fut inspir\u00e9 \u00e0 faire une retraite spirituelle dans sa maison. Il invoquait par le nom El Latif avec l&rsquo;intention d&rsquo;\u00e9carter ce qui \u00e9tait en train de descendre comme malheur et il persista \u00e0 l&rsquo;invoquer pendant des jours.<\/p>\n<p style=\"text-align: justify;\">Or, un jour alors qu&rsquo;il faisait son Dhikr, Lalla Mannana (qu\u2019Allah l\u2019agr\u00e9e) vint dans sa demeure et elle avait souvent l&rsquo;habitude de le visiter. En entrant chez lui, elle se dirigea sans dire un mot \u00e0 personne, vers le lieu o\u00f9 Sidi Banani (qu\u2019Allah l\u2019agr\u00e9e) s&rsquo;\u00e9tait isol\u00e9 pour accomplir son devoir. Elle lui dit alors, en l&rsquo;apercevant\u00a0: <span class=\"paroles\">\u00ab\u00a0<span style=\"color: #800000;\">On t&rsquo;a reconnu \u00d4\u00a0Sidi Ahmed Banani\u00a0!\u00a0<\/span>\u00bb.<\/span> Puis elle retourna d&rsquo;o\u00f9 elle \u00e9tait venue.<\/p>\n<p style=\"text-align: justify;\">Lorsqu\u2019elle revint une autre fois et qu\u2019elle s\u2019entretint avec les gens de la demeure, ils lui demand\u00e8rent\u00a0: <span class=\"paroles\">\u00ab\u00a0<span style=\"color: #800000;\">L\u2019autre jour, tu as fais ceci et cela, et tu n&rsquo;as parl\u00e9 \u00e0 aucun parmi nous, pour quelle raison\u00a0?\u00a0<\/span>\u00bb<\/span><\/p>\n<p style=\"text-align: justify;\">Alors, elle r\u00e9pondit\u00a0: <span class=\"paroles\">\u00ab\u00a0<span style=\"color: #800000;\">J\u2019ai vu descendre des cieux une calamit\u00e9 sur cette r\u00e9gion, et il ne restait qu\u2019un empan entre le ch\u00e2timent et la ville. Et j\u2019ai vu les gens apeur\u00e9s et pleins de regrets, puis elle cita ce po\u00e8me\u00a0:<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\">\u00ab\u00a0Et les vrais hommes ne sont, en v\u00e9rit\u00e9, que les vertueux,<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\">Hormis eux tous les autres ne sont que des enfants.\u00a0<\/span>\u00bb<\/p>\n<p style=\"text-align: justify;\">Puis elle continua\u00a0:<span class=\"paroles\" style=\"color: #800000;\"> Ensuite, j&rsquo;ai vu cette calamit\u00e9 s&rsquo;\u00e9lever jusqu\u2019\u00e0 ce que je perde toute trace. J\u2019ai cherch\u00e9 la raison par laquelle ce malheur s&rsquo;est \u00e9cart\u00e9, mais je n&rsquo;ai pas pu la conna\u00eetre, ni la d\u00e9celer, et ce, malgr\u00e9 un effort de recherche (par son d\u00e9voilement) consid\u00e9rable. N&rsquo;ayant pas pu en conna\u00eetre la raison, j\u2019ai fait les ablutions durant la nuit et j&rsquo;ai r\u00e9cit\u00e9 des pri\u00e8res sur le Proph\u00e8te (que la pri\u00e8re et la paix d\u2019Allah soient sur lui), puis j\u2019ai demand\u00e9 \u00e0 Allah de m&rsquo;\u00e9claircir sur cette question.<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"paroles\"><span style=\"color: #800000;\">Lorsque je me suis endormie, deux anges vinrent \u00e0 moi. Ils ont pris mes mains et m&rsquo;ont transport\u00e9e jusqu&rsquo;au lieu o\u00f9 s\u2019\u00e9tait isol\u00e9 Sidi Banani, en train de faire le Dhikr. Quand je me suis r\u00e9veill\u00e9e, je suis all\u00e9e le trouver, j\u2019ai su alors qu\u2019il \u00e9tait la cause de la suppression de cette calamit\u00e9 sur les musulmans, qu\u2019Allah le r\u00e9compense de ses biens\u00a0<\/span>\u00bb<\/span>.<\/p>\n<p style=\"text-align: justify;\">Cette noble dame a assist\u00e9 \u00e0 l&rsquo;enterrement de Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret). Trois jours avant son d\u00e9c\u00e8s, elle informa le Fqih Sidi Banani (qu\u2019Allah l\u2019agr\u00e9e) ainsi que certains m\u00e9ritants, de la mort du Sultan apr\u00e8s deux ou trois jours.<\/p>\n<p style=\"text-align: justify;\">Lorsque parvint l&rsquo;enterrement de Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) on lui demanda\u00a0: <span class=\"paroles\">\u00ab\u00a0<span style=\"color: #800000;\">Ne nous avais-tu pas dit que le Sultan allait mourir\u00a0?\u00a0<\/span>\u00bb<\/span> Elle r\u00e9pondit\u00a0: <span class=\"paroles\">\u00ab\u00a0<span style=\"color: #800000;\">Oui, et c\u2019est bien lui le Sultan<\/span>\u00a0\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\">Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) lui envoyait certains de ses compagnons qui l&rsquo;interrogeaient dans certaines situations, elle les informait sur la v\u00e9rit\u00e9 de ces situations.<\/p>\n<p style=\"text-align: justify;\">Elle est d\u00e9c\u00e9d\u00e9e apr\u00e8s la mort de Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret), peu de temps apr\u00e8s lui. Son tombeau est \u00e0 c\u00f4t\u00e9 des pressoirs se situant pr\u00e8s de la route principale, dans une mosqu\u00e9e en ruine, dans la ville de F\u00e8s. Quant \u00e0 Sidi Banani (qu\u2019Allah l\u2019agr\u00e9e), apr\u00e8s avoir consult\u00e9 Lalla Mannana (qu\u2019Allah l\u2019agr\u00e9e) il s&#8217;empressa vers ce grand bien et prit de Se\u00efdina, la Tariqa Mohamediya.<\/p>\n<p style=\"text-align: justify;\">Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) le rapprochait toujours vers lui depuis qu\u2019il avait pris la Tariqa et il questionnait \u00e0 son sujet s&rsquo;il ne le voyait pas aupr\u00e8s des fr\u00e8res. Il (qu\u2019Allah sanctifie son pr\u00e9cieux secret) appr\u00e9ciait ses paroles et ses discussions et lorsqu\u2019il \u00e9tait dans un \u00e9tat de resserrement (Qabdh) il le faisait appeler et il discutait avec lui.<\/p>\n<p style=\"text-align: justify;\">Se\u00efdina (qu\u2019Allah sanctifie son pr\u00e9cieux secret) lui disait\u00a0: <span class=\"saidina\">\u00ab\u00a0<strong><span style=\"color: #628fdb;\">Que disent les ex\u00e9g\u00e8tes au sujet de tels et tels versets\u00a0?\u00a0<\/span><\/strong>\u00bb<\/span> Et il lui r\u00e9pondait sur les dires des ex\u00e9g\u00e8tes. Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) lui certifiait les paroles de certains et en r\u00e9futait d\u2019autres qui s&rsquo;\u00e9cartaient de l&rsquo;exactitude et il justifiait la v\u00e9racit\u00e9 de ses propos \u00e0 travers des preuves r\u00e9v\u00e9l\u00e9es et logiques. Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) lui disait\u00a0: <span class=\"saidina\">\u00ab\u00a0<span style=\"color: #628fdb;\"><strong>Voil\u00e0 le but des dires des chercheurs parmi les savants de la science ext\u00e9rieure, mais quant au sens profond du verset c&rsquo;est ceci et cela\u00a0<\/strong><\/span>\u00bb<\/span><\/p>\n<p style=\"text-align: justify;\">Il parlait avec lui au sujet des nobles paroles proph\u00e9tiques avec la m\u00eame performance. Le Fqih Banani (qu\u2019Allah l\u2019agr\u00e9e) ne quittait Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) qu\u2019avec un savoir qui \u00e9blouit la raison et que ne peuvent saisir que ceux dou\u00e9s d\u2019une grande science.<\/p>\n<p style=\"text-align: justify;\">Parmi les caract\u00e9ristiques de Sidi Banani (qu\u2019Allah l\u2019agr\u00e9e), c&rsquo;est sa grande capacit\u00e9 de m\u00e9morisation. En effet, il ne connaissait pas l&rsquo;exp\u00e9rience de l&rsquo;oubli tant Allah (qu\u2019Il soit Glorifi\u00e9 et Exalt\u00e9) lui a donn\u00e9 l&rsquo;enracinement et la perfection de la m\u00e9moire. Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret) s\u2019adressait \u00e0 lui par le terme de Ma\u00eetre et quand il parlait avec lui, il suscitait l&rsquo;\u00e9tonnement de l&rsquo;audition devant sa compr\u00e9hension des propos de Se\u00efdina (qu\u2019Allah sanctifie son pr\u00e9cieux secret).<\/p>\n<p style=\"text-align: justify;\"><strong>Recherche et Traduction par la Zaouiya Tidjaniya El Koubra d\u2019Europe<\/strong><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La majdhouba (attir\u00e9e par Allah) connue Lalla Mannana. Elle fut (qu\u2019Allah lui accorde mis\u00e9ricorde), de ceux dont les pieds \u00e9taient enracin\u00e9s dans le d\u00e9voilement (Moukachafa) et son \u00e9tat de ravissement (Jadhb) prenait le dessus sur elle \u00e0 certains moments. Souvent, elle se rendait chez Sidi Ahmed ibn Mohamed El Banani (qu\u2019Allah l\u2019agr\u00e9e). Lorsque celui-ci alla [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-95","post","type-post","status-publish","format-standard","hentry","category-compagnons-cheikh-tidjani"],"blocksy_meta":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":""},"post_excerpt_stackable_v2":"<p>La majdhouba (attir\u00e9e par Allah) connue Lalla Mannana. Elle fut (qu\u2019Allah lui accorde mis\u00e9ricorde), de ceux dont les pieds \u00e9taient enracin\u00e9s dans le d\u00e9voilement (Moukachafa) et son \u00e9tat de ravissement (Jadhb) prenait le dessus sur elle \u00e0 certains moments. Souvent, elle se rendait chez Sidi Ahmed ibn Mohamed El Banani (qu\u2019Allah l\u2019agr\u00e9e). Lorsque celui-ci alla chez elle afin de la consulter sur son d\u00e9sir d\u2019entrer dans la Tariqa, elle l&rsquo;accueillit avec hospitalit\u00e9 puis lui conseilla de s&#8217;empresser de prendre la Tariqa de Se\u00efdina Ahmed Tijani (qu\u2019Allah sanctifie son pr\u00e9cieux secret). Elle lui raconta ses m\u00e9rites et ce qu\u2019elle a v\u00e9cu\u2026<\/p>\n","category_list_v2":"<a href=\"https:\/\/tidjaniya.com\/fr\/category\/sidi-ahmed-tidjani\/compagnons-cheikh-tidjani\/\" rel=\"category tag\">Compagnons de Cheikh Tijani<\/a>","author_info_v2":{"name":"Samia Ajdid","url":"https:\/\/tidjaniya.com\/fr\/author\/samia-ajdid\/"},"comments_num_v2":"0 commentaire","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Samia Ajdid","author_link":"https:\/\/tidjaniya.com\/fr\/author\/samia-ajdid\/"},"uagb_comment_info":0,"uagb_excerpt":"La majdhouba (attir\u00e9e par Allah) connue Lalla Mannana. Elle fut (qu\u2019Allah lui accorde mis\u00e9ricorde), de ceux dont les pieds \u00e9taient enracin\u00e9s dans le d\u00e9voilement (Moukachafa) et son \u00e9tat de ravissement (Jadhb) prenait le dessus sur elle \u00e0 certains moments. Souvent, elle se rendait chez Sidi Ahmed ibn Mohamed El Banani (qu\u2019Allah l\u2019agr\u00e9e). Lorsque celui-ci alla\u2026","_links":{"self":[{"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/posts\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/comments?post=95"}],"version-history":[{"count":0,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/posts\/95\/revisions"}],"wp:attachment":[{"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/media?parent=95"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/categories?post=95"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tidjaniya.com\/fr\/wp-json\/wp\/v2\/tags?post=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}